{"id":11715,"date":"2025-12-15T11:06:01","date_gmt":"2025-12-15T16:06:01","guid":{"rendered":"https:\/\/www.cga.ca\/?post_type=energy-magazine-post&#038;p=11715"},"modified":"2025-12-15T11:06:01","modified_gmt":"2025-12-15T16:06:01","slug":"un-esprit-daventure-tres-developpe","status":"publish","type":"energy-magazine-post","link":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/","title":{"rendered":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9"},"content":{"rendered":"<h2><em>Anim\u00e9 par un enthousiasme pour l\u2019\u00e9nergie et un d\u00e9sir d\u2019apprendre, David\u00a0Morton poursuit sa carri\u00e8re en travaillant sur des questions li\u00e9es \u00e0 la fiabilit\u00e9 \u00e9nerg\u00e9tique.<\/em><\/h2>\n<p><em>Par Graham\u00a0Chandler<\/em><\/p>\n<p>\u00ab\u00a0J\u2019ai toujours \u00e9t\u00e9 int\u00e9ress\u00e9 par l\u2019\u00e9nergie \u2013 c\u2019est l\u2019une des raisons qui m\u2019ont pouss\u00e9 \u00e0 me diriger vers le g\u00e9nie m\u00e9canique\u00a0\u00bb\u00a0[traduction], explique David Morton, ing., ICD.D. Il est actuellement pr\u00e9sident-directeur g\u00e9n\u00e9ral du Canadian Energy Reliability Council \u00a0(CERC), cadre en r\u00e9sidence chez \u00c9nergie Positive \u00e0 l\u2019Universit\u00e9 d\u2019Ottawa et pr\u00e9sident de l\u2019International Confederation of Energy Regulators (ICER).<\/p>\n<p>\u00ab\u00a0Mon premier point d\u2019entr\u00e9e dans l\u2019industrie de l\u2019\u00e9nergie a \u00e9t\u00e9 la r\u00e8glementation des services publics, explique-t-il. Les entreprises de services publics sont souvent les seuls fournisseurs de services \u00e9nerg\u00e9tiques dans une r\u00e9gion. Cela en fait ce que les \u00e9conomistes appellent des <em>fournisseurs monopolistiques<\/em>, dont les tarifs ne sont g\u00e9n\u00e9ralement pas soumis \u00e0 l\u2019influence du march\u00e9 exerc\u00e9e par un concurrent. Cela expose potentiellement les clients au risque de payer trop cher ou de recevoir un service qui n\u2019est pas optimal.\u00a0\u00bb\u00a0[Traduction]\n<p>Les organismes de r\u00e8glementation des services publics sont avant tout des \u00ab\u00a0organismes de r\u00e8glementation \u00e9conomique\u00a0\u00bb et leur r\u00f4le consiste \u00e0 se substituer aux forces du march\u00e9 afin de prot\u00e9ger les clients, explique-t-il. Ils doivent \u00e9galement veiller \u00e0 ce que les services publics per\u00e7oivent suffisamment de recettes pour leur permettre de d\u00e9gager un rendement \u00e9quitable des investissements g\u00e9n\u00e9ralement consid\u00e9rables qu\u2019ils doivent r\u00e9aliser dans les infrastructures.<\/p>\n<p>\u00ab\u00a0C\u2019est cette n\u00e9cessit\u00e9 d\u2019\u00e9quilibrer les int\u00e9r\u00eats \u00e9conomiques qui m\u2019int\u00e9resse, en plus de mon int\u00e9r\u00eat g\u00e9n\u00e9ral pour l\u2019\u00e9nergie, explique M.\u00a0Morton. Les aspects d\u2019int\u00e9r\u00eat public qui consistent \u00e0 faire en sorte que les entreprises de services publics fournissent une \u00e9nergie s\u00fbre et fiable, qu\u2019elles puissent obtenir un rendement \u00e9quitable et que le public soit prot\u00e9g\u00e9 contre tout exc\u00e8s des fournisseurs monopolistiques sont stimulants, int\u00e9ressants et, lorsqu\u2019on y parvient, gratifiants.\u00a0\u00bb (Traduction) Et c\u2019est ce qui a guid\u00e9 sa carri\u00e8re.<\/p>\n<figure id=\"attachment_11689\" style=\"width: 200px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11689 size-medium\" src=\"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/David-Morton-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/David-Morton-200x300.jpg 200w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/David-Morton.jpg 512w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption class=\"wp-caption-text\"><span>M. David Morton, ing., ICD.D., est pr\u00e9sident-directeur g\u00e9n\u00e9ral du Canadian Energy Reliability Council (CERC), cadre en r\u00e9sidence chez \u00c9nergie positive \u00e0 l\u2019Universit\u00e9 d\u2019Ottawa et pr\u00e9sident de l\u2019International Confederation of Energy Regulators (ICER).<\/span><\/figcaption><\/figure>\n<p>David Morton est n\u00e9 au Royaume-Uni et y a v\u00e9cu jusqu\u2019\u00e0 l\u2019\u00e2ge de 9 ans, lorsque sa famille a d\u00e9m\u00e9nag\u00e9 au Canada. \u00ab Mes parents avaient une certaine envie de voyager, et j\u2019ai fini par aller \u00e0 l\u2019\u00e9cole \u00e0 Thunder Bay (Winnipeg) et \u00e0 Orlando (Floride), et dans plusieurs endroits du Sud de l\u2019Ontario \u00bb [traduction], explique-t-il. Cette envie de voyager s\u2019est \u00e9galement manifest\u00e9e dans ses choix de carri\u00e8re, qui ont d\u00e9but\u00e9 par un baccalaur\u00e9at en sciences et en g\u00e9nie m\u00e9canique \u00e0 l\u2019Universit\u00e9 de Toronto en 1977.<\/p>\n<p>Avant de travailler dans les secteurs de l\u2019industrie de l\u2019\u00e9nergie et des services publics, il a consacr\u00e9 une grande partie de sa carri\u00e8re \u00e0 l\u2019informatique. \u00ab\u00a0Tout a commenc\u00e9 par un int\u00e9r\u00eat pour ce qu\u2019on appelait souvent l\u2019informatique visuelle \u00e0 la fin des ann\u00e9es 1970 et au d\u00e9but des ann\u00e9es 1980, explique-t-il. J\u2019ai cofond\u00e9 une entreprise afin de d\u00e9velopper des logiciels permettant de cr\u00e9er des simulations et des mod\u00e8les visuels. \u00c0 l\u2019\u00e9poque, cela repr\u00e9sentait une v\u00e9ritable r\u00e9volution dans un monde o\u00f9 les ordinateurs personnels venaient tout juste d\u2019appara\u00eetre et n\u2019affichaient qu\u2019un nombre limit\u00e9 de caract\u00e8res sur un <em>\u00e9cran vert<\/em>. J\u2019ai utilis\u00e9 le logiciel que nous avions d\u00e9velopp\u00e9 pour cr\u00e9er des mod\u00e8les pour divers projets, notamment l\u2019agrandissement du terminal et la construction d\u2019une deuxi\u00e8me piste \u00e0 l\u2019a\u00e9roport de Vancouver.\u00a0\u00bb\u00a0[Traduction]\n<p>Le succ\u00e8s de ce projet l\u2019a incit\u00e9 \u00e0 poursuivre une carri\u00e8re dans le domaine en plein essor des technologies de l\u2019information. \u00ab\u00a0J\u2019ai g\u00e9r\u00e9 divers projets de d\u00e9veloppement informatique pour des entreprises et des organismes gouvernementaux, raconte-t-il. Bon nombre d\u2019entre eux \u00e9taient con\u00e7us sur mesure et exigeaient une bonne compr\u00e9hension des besoins des utilisateurs du syst\u00e8me et de la capacit\u00e9 du logiciel \u00e0 r\u00e9pondre \u00e0 ces besoins, compte tenu des contraintes budg\u00e9taires du projet.\u00a0\u00bb\u00a0[Traduction]\n<p>En 2010, il a appris qu\u2019un poste de commissaire \u00e0 temps partiel \u00e9tait vacant \u00e0 la BC Utilities Commission (BCUC). Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 et s\u2019est dit : \u00ab\u00a0Je pourrais int\u00e9grer cela \u00e0 mon autre travail, cependant, le travail \u00e9tait si int\u00e9ressant que j\u2019ai fini par prendre en charge de plus en plus de dossiers. Puis, environ cinq ans plus tard, le poste de pr\u00e9sident-directeur g\u00e9n\u00e9ral s\u2019est lib\u00e9r\u00e9 et j\u2019ai pos\u00e9 ma candidature, qui a \u00e9t\u00e9 retenue. Ce poste m\u2019a permis de mettre mes comp\u00e9tences en leadership au service de tous les Britanno-Colombiens. Ce fut un honneur d\u2019\u00eatre l\u2019un des dirigeants ayant les plus longs \u00e9tats de service \u00e0 la BCUC. L\u2019une des consid\u00e9rations est l\u2019\u00e9chelle et la port\u00e9e de l\u2019\u00e9nergie fournie par le gaz naturel, explique-t-il. Celui-ci fournit actuellement plus d\u2019\u00e9nergie que l\u2019\u00e9lectricit\u00e9, et certaines des utilisations du gaz naturel sont tr\u00e8s difficiles \u00e0 satisfaire avec l\u2019\u00e9lectricit\u00e9, comme la fabrication de ciment, par exemple.\u00a0\u00bb\u00a0[Traduction]\n<p>Bien qu\u2019il soit th\u00e9oriquement possible de remplacer le gaz naturel par l\u2019\u00e9lectricit\u00e9, cela impliquerait au minimum de doubler la quantit\u00e9 d\u2019\u00e9lectricit\u00e9 que nous produisons actuellement au Canada, explique M.\u00a0Morton. \u00ab\u00a0Et ce doublement s\u2019inscrit dans un contexte o\u00f9 nous pourrions \u00e9galement avoir besoin d\u2019\u00e9lectricit\u00e9 suppl\u00e9mentaire si nous d\u00e9cidons d\u2019\u00e9lectrifier notre r\u00e9seau de transport en rempla\u00e7ant les carburants \u00e0 base de p\u00e9trole par l\u2019\u00e9lectricit\u00e9 et si nous d\u00e9cidons aussi d\u2019\u00e9lectrifier la liqu\u00e9faction du gaz naturel afin de d\u00e9velopper un secteur d\u2019exportation de GNL. De plus, tout cela s\u2019ajoute \u00e0 la fourniture de quantit\u00e9s croissantes d\u2019\u00e9lectricit\u00e9 pour alimenter les centres de donn\u00e9es et les processus d\u2019intelligence artificielle (IA), et pour r\u00e9pondre \u00e0 la demande croissante d\u2019\u00e9lectricit\u00e9 d\u2019une population en augmentation, ajoute-t-il. M\u00eame s\u2019il ne faut jamais dire jamais, compte tenu de l\u2019\u00e9tat actuel de la technologie et des infrastructures \u00e9nerg\u00e9tiques, il est peu probable que le Canada abandonne le gaz naturel comme ressource\u00a0\u00bb,\u00a0conclut-il. [Traduction]\n<figure id=\"attachment_11691\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11691 size-full\" src=\"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1422\" srcset=\"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg 2560w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-300x167.jpg 300w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-1024x569.jpg 1024w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-768x427.jpg 768w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-1536x853.jpg 1536w, https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-2048x1138.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-caption-text\"><span>\u00ab Compte tenu de l\u2019\u00e9tat actuel de la technologie et des infrastructures \u00e9nerg\u00e9tiques, il est peu probable que le Canada abandonne le gaz naturel comme ressource. \u00bb [Traduction]<\/span><\/figcaption><\/figure>\u00ab\u00a0Je ne suis pas favorable \u00e0 l\u2019opposition du gaz naturel \u00e0 l\u2019\u00e9lectricit\u00e9, ajoute M.\u00a0Morton. Je m\u2019efforce d\u2019adopter une vision \u00e9quilibr\u00e9e et de poser les questions difficiles. Je pense que nous devons garder l\u2019esprit ouvert et \u00eatre conscients des d\u00e9fis et des limites de chaque source d\u2019\u00e9nergie. Je si\u00e8ge au conseil d\u2019administration du Western Electricity Coordinating Council, qui est charg\u00e9 de veiller au respect et \u00e0 l\u2019application des normes de fiabilit\u00e9 \u00e9lectrique dans une r\u00e9gion appel\u00e9e <em>western interconnect<\/em>, qui comprend 17\u00a0\u00c9tats am\u00e9ricains ainsi que certaines parties du Nord du Mexique, de la Colombie-Britannique et de l\u2019Alberta. La fiabilit\u00e9 de l\u2019\u00e9lectricit\u00e9 est donc un sujet qui me tient \u00e0 c\u0153ur, tout comme la fiabilit\u00e9 \u00e9nerg\u00e9tique en g\u00e9n\u00e9ral.\u00a0\u00bb\u00a0[Traduction]\n<p>M. Morton affirme que son d\u00e9sir d\u2019\u00e9quilibre s\u2019\u00e9tend \u00e0 son mode de vie. \u00ab Le travail est important pour cet \u00e9quilibre, et pour qu\u2019il soit r\u00e9ussi, il faut aimer ce que l\u2019on fait. J\u2019ai l\u2019immense chance de pouvoir dire que je suis passionn\u00e9 par le travail que je continue \u00e0 faire, m\u00eame si j\u2019ai d\u00e9pass\u00e9 l\u2019\u00e2ge de la retraite. \u00bb [Traduction]\n<p>Par exemple, David continue de collaborer avec ses coll\u00e8gues du milieu de la r\u00e8glementation \u00e0 l\u2019\u00e9chelle internationale en tant que pr\u00e9sident b\u00e9n\u00e9vole de l\u2019International Confederation of Energy Regulators (ICER).<\/p>\n<p>Mais ce n\u2019est pas tout : \u00ab\u00a0J\u2019ai r\u00e9cemment lanc\u00e9 une nouvelle initiative appel\u00e9e le Canadian Energy Reliability Council, ajoute-t-il. Le Council a pour mission de cr\u00e9er de nouveaux mod\u00e8les de collaboration \u00e0 l\u2019\u00e9chelle du r\u00e9seau \u00e9nerg\u00e9tique et de contribuer \u00e0 red\u00e9finir la fa\u00e7on dont les d\u00e9cideurs politiques et le public per\u00e7oivent la fiabilit\u00e9, pr\u00e9cise-t-il. La fiabilit\u00e9 \u00e9nerg\u00e9tique est un sujet qui nous concerne tous, mais qui semble souvent passer au second plan derri\u00e8re d\u2019autres questions jug\u00e9es plus urgentes. Je suis tr\u00e8s heureux de pouvoir mener \u00e0 bien cette initiative.\u00a0\u00bb\u00a0[Traduction]\n<p>Une autre r\u00e9alisation dont il est fier est sa participation r\u00e9guli\u00e8re \u00e0 des conf\u00e9rences et \u00e0 des formations internationales destin\u00e9es \u00e0 d\u2019autres organismes de r\u00e8glementation \u00e0 travers le monde. \u00ab\u00a0J\u2019ai collabor\u00e9 avec des organismes de r\u00e8glementation et des gouvernements au Botswana, en Mac\u00e9doine, en Zambie, en Namibie, en Moldavie, au Sri Lanka, en Argentine, en Bosnie, en Dominique, en Papouasie-Nouvelle-Guin\u00e9e, au Br\u00e9sil, au Kazakhstan et au Bangladesh.\u00a0\u00bb\u00a0[Traduction]\n<p>En plus de ces activit\u00e9s et de nombreuses autres activit\u00e9s paraprofessionnelles, \u00ab\u00a0l\u2019un de mes passe-temps consiste \u00e0 essayer de comprendre l\u2019histoire, explique-t-il. Comme l\u2019a dit le philosophe espagnol George Santayana : ceux qui ne peuvent se souvenir du pass\u00e9 sont condamn\u00e9s \u00e0 le r\u00e9p\u00e9ter. Je pense qu\u2019\u00e0 bien des \u00e9gards, nous sommes \u00e0 la crois\u00e9e des chemins et qu\u2019en tant que soci\u00e9t\u00e9, nous sommes trop prompts \u00e0 ignorer les le\u00e7ons de l\u2019histoire.\u00a0\u00bb [Traduction]\n<p>Ainsi, cet esprit familial d\u2019aventure n\u2019a jamais vraiment quitt\u00e9 David. M\u00eame s\u2019il s\u2019exprime sous des formes l\u00e9g\u00e8rement diff\u00e9rentes, il est toujours pr\u00e9sent. \u00ab\u00a0Lorsque je ne suis pas occup\u00e9 par des activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9nergie ou aux services publics, j\u2019appr\u00e9cie voyager, tant au niveau local qu\u2019international, explique-t-il. J\u2019ai la chance de vivre dans une r\u00e9gion magnifique du monde, je ne me lasse jamais des paysages de la c\u00f4te Ouest. Je trouve que voyager \u00e0 l\u2019\u00e9tranger m\u2019ouvre les yeux et l\u2019esprit \u00e0 d\u2019autres cultures et d\u2019autres perspectives. C\u2019est \u00e9galement l\u2019occasion d\u2019en apprendre davantage sur l\u2019histoire commune qui nous unit tous.\u00a0\u00bb\u00a0[Traduction]\n","protected":false},"author":110,"featured_media":11691,"menu_order":25,"template":"","energy-magazine-category":[64],"feature":[],"issue-category":[173],"coauthors":[120],"class_list":["post-11715","energy-magazine-post","type-energy-magazine-post","status-publish","has-post-thumbnail","hentry","energy-magazine-category-profil-chef-de-file-de-lindustrie","issue-category-numero-2-2025"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association\" \/>\n<meta property=\"og:description\" content=\"Anim\u00e9 par un enthousiasme pour l\u2019\u00e9nergie et un d\u00e9sir d\u2019apprendre, David\u00a0Morton poursuit sa carri\u00e8re en travaillant sur des questions li\u00e9es \u00e0 la fiabilit\u00e9 \u00e9nerg\u00e9tique. Par Graham\u00a0Chandler \u00ab\u00a0J\u2019ai toujours \u00e9t\u00e9 int\u00e9ress\u00e9 par l\u2019\u00e9nergie \u2013 c\u2019est l\u2019une des raisons qui m\u2019ont pouss\u00e9 \u00e0 me diriger vers le g\u00e9nie m\u00e9canique\u00a0\u00bb\u00a0[traduction], explique David Morton, ing., ICD.D. Il est actuellement...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Gas Association\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Graham Chandler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/\"},\"author\":{\"name\":\"Steven Liu\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#\\\/schema\\\/person\\\/fe2544326cc9c4f35448a734d70af5c7\"},\"headline\":\"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9\",\"datePublished\":\"2025-12-15T16:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/\"},\"wordCount\":1766,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/\",\"url\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/\",\"name\":\"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\",\"datePublished\":\"2025-12-15T16:06:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg\",\"width\":2560,\"height\":1422,\"caption\":\"Gas tap with pipeline system at natural gas station. Industry\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/un-esprit-daventure-tres-developpe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energy Magazine Articles\",\"item\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/energy-magazine-post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.cga.ca\\\/\",\"name\":\"Canadian Gas Association\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cga.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#organization\",\"name\":\"Canadian Gas Association\",\"url\":\"https:\\\/\\\/www.cga.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cga-logo-only.png\",\"contentUrl\":\"https:\\\/\\\/www.cga.ca\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cga-logo-only.png\",\"width\":696,\"height\":696,\"caption\":\"Canadian Gas Association\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cga.ca\\\/#\\\/schema\\\/person\\\/fe2544326cc9c4f35448a734d70af5c7\",\"name\":\"Steven Liu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g8d3fc89b60bb53b3cec9a69fccd28d83\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g\",\"caption\":\"Steven Liu\"},\"url\":\"https:\\\/\\\/www.cga.ca\\\/fr\\\/author\\\/sliu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/","og_locale":"fr_FR","og_type":"article","og_title":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association","og_description":"Anim\u00e9 par un enthousiasme pour l\u2019\u00e9nergie et un d\u00e9sir d\u2019apprendre, David\u00a0Morton poursuit sa carri\u00e8re en travaillant sur des questions li\u00e9es \u00e0 la fiabilit\u00e9 \u00e9nerg\u00e9tique. Par Graham\u00a0Chandler \u00ab\u00a0J\u2019ai toujours \u00e9t\u00e9 int\u00e9ress\u00e9 par l\u2019\u00e9nergie \u2013 c\u2019est l\u2019une des raisons qui m\u2019ont pouss\u00e9 \u00e0 me diriger vers le g\u00e9nie m\u00e9canique\u00a0\u00bb\u00a0[traduction], explique David Morton, ing., ICD.D. Il est actuellement...","og_url":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/","og_site_name":"Canadian Gas Association","og_image":[{"width":2560,"height":1422,"url":"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes","Written by":"Graham Chandler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#article","isPartOf":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/"},"author":{"name":"Steven Liu","@id":"https:\/\/www.cga.ca\/#\/schema\/person\/fe2544326cc9c4f35448a734d70af5c7"},"headline":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9","datePublished":"2025-12-15T16:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/"},"wordCount":1766,"publisher":{"@id":"https:\/\/www.cga.ca\/#organization"},"image":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/","url":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/","name":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9 | Canadian Gas Association","isPartOf":{"@id":"https:\/\/www.cga.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#primaryimage"},"image":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg","datePublished":"2025-12-15T16:06:01+00:00","breadcrumb":{"@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#primaryimage","url":"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg","contentUrl":"https:\/\/www.cga.ca\/wp-content\/uploads\/2025\/12\/Gas-tap-pipeline-iStock-1275086161-scaled.jpg","width":2560,"height":1422,"caption":"Gas tap with pipeline system at natural gas station. Industry"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/un-esprit-daventure-tres-developpe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cga.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Energy Magazine Articles","item":"https:\/\/www.cga.ca\/fr\/energy-magazine-post\/"},{"@type":"ListItem","position":3,"name":"Un esprit d\u2019aventure tr\u00e8s d\u00e9velopp\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.cga.ca\/#website","url":"https:\/\/www.cga.ca\/","name":"Canadian Gas Association","description":"","publisher":{"@id":"https:\/\/www.cga.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cga.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cga.ca\/#organization","name":"Canadian Gas Association","url":"https:\/\/www.cga.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cga.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.cga.ca\/wp-content\/uploads\/2023\/08\/cga-logo-only.png","contentUrl":"https:\/\/www.cga.ca\/wp-content\/uploads\/2023\/08\/cga-logo-only.png","width":696,"height":696,"caption":"Canadian Gas Association"},"image":{"@id":"https:\/\/www.cga.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cga.ca\/#\/schema\/person\/fe2544326cc9c4f35448a734d70af5c7","name":"Steven Liu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g8d3fc89b60bb53b3cec9a69fccd28d83","url":"https:\/\/secure.gravatar.com\/avatar\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35cd7aa4e615ea78d08dad974670d35fcd2f619100dc159ae60a6601d034d635?s=96&d=mm&r=g","caption":"Steven Liu"},"url":"https:\/\/www.cga.ca\/fr\/author\/sliu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/energy-magazine-post\/11715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/energy-magazine-post"}],"about":[{"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/types\/energy-magazine-post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/users\/110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/media\/11691"}],"wp:attachment":[{"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/media?parent=11715"}],"wp:term":[{"taxonomy":"energy-magazine-category","embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/energy-magazine-category?post=11715"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/feature?post=11715"},{"taxonomy":"issue-category","embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/issue-category?post=11715"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.cga.ca\/fr\/wp-json\/wp\/v2\/coauthors?post=11715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}